{"id":16333,"date":"2026-03-31T14:07:47","date_gmt":"2026-03-31T14:07:47","guid":{"rendered":"https:\/\/numenit.com\/?post_type=news&#038;p=16333"},"modified":"2026-03-31T14:07:47","modified_gmt":"2026-03-31T14:07:47","slug":"numen-registra-crescimento-de-23-em-2025","status":"publish","type":"news","link":"https:\/\/numenit.com\/pt-br\/news\/numen-registra-crescimento-de-23-em-2025\/","title":{"rendered":"Numen registra crescimento de 23% em 2025"},"content":{"rendered":"<p>Mais do que planejar, \u00e9 preciso colocar a estrat\u00e9gia em pr\u00e1tica. Foi a partir dessa premissa que a Numen, l\u00edder em solu\u00e7\u00f5es tecnol\u00f3gicas, obteve um desempenho robusto em 2025. A empresa encerrou o ano com um crescimento de 23% no faturamento e de 20% em seu capital humano. Para 2026, considera-se uma proje\u00e7\u00e3o de 22% de alta.<\/p>\n<p>&nbsp;<\/p>\n<p>Com 16 anos de experi\u00eancia, a Numen \u00e9 reconhecida pela abordagem inovadora e pelo foco consistente em apoiar empresas na transforma\u00e7\u00e3o digital e na gera\u00e7\u00e3o de valor sustent\u00e1vel. O balan\u00e7o positivo de 2025 \u00e9 fruto de uma s\u00e9rie de movimentos estrat\u00e9gicos bem executados.<\/p>\n<p>&nbsp;<\/p>\n<p>Enquanto o mercado enfrenta escassez de m\u00e3o de obra, a consultoria investiu fortemente na forma\u00e7\u00e3o de talentos, promovendo capacita\u00e7\u00e3o t\u00e9cnica e comportamental. Em parceria com a Prosper Digital Skills, lan\u00e7ou o PlurAll Edi\u00e7\u00e3o PCDs, seu primeiro programa de forma\u00e7\u00e3o exclusivo para pessoas com defici\u00eancia, que resultou na capacita\u00e7\u00e3o de mais de 30 profissionais.<\/p>\n<p>&nbsp;<\/p>\n<p>Refor\u00e7ando o pilar de que n\u00e3o existe inova\u00e7\u00e3o sem diversidade, a consultoria desenvolveu o \u201cFeNUMENalls\u201d, projeto que engloba cinco comit\u00eas: diversidade e inclus\u00e3o, voltado para pessoas LGBTQIAPN+, pessoas com defici\u00eancia, pessoas pretas, mulheres e profissionais 50+. Os comit\u00eas permitem que as demandas desses grupos sejam ouvidas de forma estruturada, com propostas de melhorias que v\u00e3o desde pol\u00edticas internas at\u00e9 programas de desenvolvimento e sensibiliza\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Para consolidar o plano de expans\u00e3o, a Numen tamb\u00e9m investiu na contrata\u00e7\u00e3o de executivos para as \u00e1reas de opera\u00e7\u00f5es, vendas, marketing e pessoas. Segundo Andreia Tsuruhame, CEO da Numen, a chegada desses l\u00edderes fortaleceu a estrutura operacional. \u201cPara entregarmos o desempenho esperado, era necess\u00e1rio um preparo pr\u00e9vio. Esses profissionais fortaleceram nossa base e nos deram a sustenta\u00e7\u00e3o necess\u00e1ria para ampliarmos nossas frentes de servi\u00e7o\u201d, explica.<\/p>\n<p>&nbsp;<\/p>\n<p>A performance das unidades de neg\u00f3cio tamb\u00e9m foi um fator determinante. A \u00e1rea de Digital Solutions cresceu 64%, enquanto a de Smart Services (AMS) saltou 83%. J\u00e1 a Moovi, plataforma de cursos SAP, superou a marca de dois mil alunos atendidos em 2025.<\/p>\n<p>&nbsp;<\/p>\n<p>No entanto, grande destaque do ano ficou com a cria\u00e7\u00e3o da \u00e1rea de Lean Services, respons\u00e1vel pela oferta SAP Cloud ERP. Em menos de um ano, a unidade conquistou 22 novos clientes. Como resultado, a Numen, que hoje \u00e9 a segunda maior parceira da multinacional alem\u00e3 no pa\u00eds, conquistou o primeiro lugar em vendas da solu\u00e7\u00e3o para o Brasil e Am\u00e9rica Latina e Caribe (LAC).<\/p>\n<p>&nbsp;<\/p>\n<p>A regionaliza\u00e7\u00e3o tamb\u00e9m foi prioridade. Para ampliar a presen\u00e7a nacional, a Numen abriu novas filiais no Esp\u00edrito Santo e Goi\u00e1s \u2014 esta \u00faltima, em apenas cinco meses de opera\u00e7\u00e3o, j\u00e1 representa 5% do faturamento total. Para 2026, o objetivo \u00e9 expandir para o Norte e Nordeste.<\/p>\n<p>&nbsp;<\/p>\n<p>No cen\u00e1rio internacional, onde atua h\u00e1 sete anos nos Estados Unidos e h\u00e1 dois em Portugal, as opera\u00e7\u00f5es cresceram 48%, representando 15% da receita global do grupo. \u201cVemos um grande potencial de expans\u00e3o l\u00e1 fora. Nosso objetivo, al\u00e9m de obter receita em moedas fortes, \u00e9 consolidar uma opera\u00e7\u00e3o capaz de atender nossos clientes em escala global\u201d, pontua Andreia.<\/p>\n<p>&nbsp;<\/p>\n<p>Engajada em diversificar o portf\u00f3lio, a Numen tamb\u00e9m adquiriu recentemente 25% das opera\u00e7\u00f5es da Backlgrs, parceira estrat\u00e9gica para solu\u00e7\u00f5es Salesforce. Neste ano, a consultoria pretende seguir com novos investimentos e aquisi\u00e7\u00f5es de organiza\u00e7\u00f5es verticalizadas que possuam sinergia com o neg\u00f3cio.<\/p>\n<p>&nbsp;<\/p>\n<p>Em 2026, a meta \u00e9 consolidar os resultados, ampliar a base de clientes em nuvem, intensificar os investimentos em IA e ofertar solu\u00e7\u00f5es de moderniza\u00e7\u00e3o. \u201cO investimento \u00e1rduo de 2025 nos deu escalabilidade. Agora, o desafio \u00e9 aplicar uma governan\u00e7a que mantenha o ritmo, a clareza e o alinhamento estrat\u00e9gico entre todos os times\u201d, finaliza a CEO.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amplia\u00e7\u00e3o do portf\u00f3lio, regionaliza\u00e7\u00e3o e expans\u00e3o de 20% no quadro de colaboradores est\u00e3o entre os destaques do ano<\/p>\n","protected":false},"author":6,"featured_media":16334,"parent":0,"menu_order":0,"template":"","format":"standard","news":[142],"class_list":["post-16333","news","type-news","status-publish","format-standard","has-post-thumbnail","hentry","news-negocios"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Numen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:site_name\" content=\"Numen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":null,\"url\":\"\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/numenit.com\\\/pt-br\\\/#website\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/numenit.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/numenit.com\\\/pt-br\\\/\",\"name\":\"Numen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/numenit.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Numen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"pt_BR","og_type":"article","og_site_name":"Numen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":null,"url":"","name":"","isPartOf":{"@id":"https:\/\/numenit.com\/pt-br\/#website"},"inLanguage":"pt-BR"},{"@type":"WebSite","@id":"https:\/\/numenit.com\/pt-br\/#website","url":"https:\/\/numenit.com\/pt-br\/","name":"Numen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/numenit.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/numenit.com\/pt-br\/wp-json\/wp\/v2\/news\/16333"}],"collection":[{"href":"https:\/\/numenit.com\/pt-br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/numenit.com\/pt-br\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/numenit.com\/pt-br\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":1,"href":"https:\/\/numenit.com\/pt-br\/wp-json\/wp\/v2\/news\/16333\/revisions"}],"predecessor-version":[{"id":16336,"href":"https:\/\/numenit.com\/pt-br\/wp-json\/wp\/v2\/news\/16333\/revisions\/16336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/numenit.com\/pt-br\/wp-json\/wp\/v2\/media\/16334"}],"wp:attachment":[{"href":"https:\/\/numenit.com\/pt-br\/wp-json\/wp\/v2\/media?parent=16333"}],"wp:term":[{"taxonomy":"news","embeddable":true,"href":"https:\/\/numenit.com\/pt-br\/wp-json\/wp\/v2\/news?post=16333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}